{"id":1654,"date":"2026-04-08T11:13:08","date_gmt":"2026-04-08T09:13:08","guid":{"rendered":"https:\/\/gh-parts.eu\/?p=1654"},"modified":"2026-04-08T11:14:32","modified_gmt":"2026-04-08T09:14:32","slug":"besuchen-sie-uns-auf-der-ttm-2026","status":"publish","type":"post","link":"https:\/\/gh-parts.eu\/de\/besuchen-sie-uns-auf-der-ttm-2026\/","title":{"rendered":"Besuchen Sie uns auf der TTM 2026!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1648 size-full\" src=\"https:\/\/gh-parts.eu\/wp-content\/uploads\/2026\/04\/Czekamy-wlasnie-na-ciebie-1.png\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/gh-parts.eu\/wp-content\/uploads\/2026\/04\/Czekamy-wlasnie-na-ciebie-1.png 600w, https:\/\/gh-parts.eu\/wp-content\/uploads\/2026\/04\/Czekamy-wlasnie-na-ciebie-1-300x300.png 300w, https:\/\/gh-parts.eu\/wp-content\/uploads\/2026\/04\/Czekamy-wlasnie-na-ciebie-1-150x150.png 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p data-olk-copy-source=\"MessageBody\">Wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass GH-Parts auf der\u00a0<span class=\"x_gmail-hover:entity-accent x_entity-underline x_gmail-inline x_gmail-cursor-pointer x_gmail-align-baseline\"><span class=\"x_gmail-whitespace-normal\">Targi Techniki Motoryzacyjnej 2026<\/span><\/span>\u00a0vertreten sein wird, die vom\u00a0<strong>23.\u201326. April 2026<\/strong>\u00a0in\u00a0<span class=\"x_gmail-hover:entity-accent x_entity-underline x_gmail-inline x_gmail-cursor-pointer x_gmail-align-baseline\"><span class=\"x_gmail-whitespace-normal\">Pozna\u0144<\/span><\/span>\u00a0stattfindet.<\/p>\n<p>\ud83d\udccd\u00a0<strong>Halle:<\/strong>\u00a08A<br \/>\n\ud83d\udccd\u00a0<strong>Stand:<\/strong>\u00a027<\/p>\n<p>Entdecken Sie unsere Fahrwerksl\u00f6sungen, einschlie\u00dflich kompletter MacPherson-Federbeine f\u00fcr mehr Sicherheit, Komfort und Zuverl\u00e4ssigkeit.<\/p>\n<p>\ud83d\udc49 Besuchen Sie uns:<\/p>\n<ul>\n<li>lernen Sie unsere Produkte kennen<\/li>\n<li>sprechen Sie mit unserem Team<\/li>\n<li>kn\u00fcpfen Sie neue Kontakte<\/li>\n<\/ul>\n<p>Wir freuen uns auf Sie!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Wir freuen uns, Ihnen mitteilen zu k\u00f6nnen, dass GH-Parts auf der\u00a0Targi Techniki Motoryzacyjnej 2026\u00a0vertreten sein wird, die vom\u00a023.\u201326. April 2026\u00a0in\u00a0Pozna\u0144\u00a0stattfindet. \ud83d\udccd\u00a0Halle:\u00a08A \ud83d\udccd\u00a0Stand:\u00a027 Entdecken Sie unsere Fahrwerksl\u00f6sungen, einschlie\u00dflich kompletter MacPherson-Federbeine f\u00fcr mehr Sicherheit, Komfort und Zuverl\u00e4ssigkeit. \ud83d\udc49 Besuchen Sie uns: lernen Sie unsere Produkte kennen sprechen Sie mit unserem Team kn\u00fcpfen Sie neue Kontakte Wir [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1654","post","type-post","status-publish","format-standard","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/posts\/1654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/comments?post=1654"}],"version-history":[{"count":2,"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/posts\/1654\/revisions"}],"predecessor-version":[{"id":1656,"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/posts\/1654\/revisions\/1656"}],"wp:attachment":[{"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/media?parent=1654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/categories?post=1654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gh-parts.eu\/de\/wp-json\/wp\/v2\/tags?post=1654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}